{"id":15694,"date":"2023-08-13T10:06:07","date_gmt":"2023-08-13T03:06:07","guid":{"rendered":"https:\/\/lc.mahidol.ac.th\/?post_type=research-matter&#038;p=15694"},"modified":"2025-05-01T13:48:01","modified_gmt":"2025-05-01T06:48:01","slug":"asean-university-network","status":"publish","type":"research-matter","link":"https:\/\/lc.mahidol.ac.th\/en\/research-matter\/asean-university-network\/","title":{"rendered":"ASEAN University Network on Culture and the Arts"},"content":{"rendered":"\n<p class=\"text-justify wp-block-paragraph\">ASEAN University Network on Culture and the Arts \u0e2b\u0e23\u0e37\u0e2d AUN-CA \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 (ASEAN University Network) \u0e41\u0e25\u0e30\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19+3 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e14\u0e23.\u0e2a\u0e01\u0e32\u0e27\u0e23\u0e38\u0e49\u0e07 \u0e2a\u0e32\u0e22\u0e1a\u0e38\u0e0d\u0e21\u0e35 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"934\" src=\"https:\/\/lc.mahidol.ac.th\/wp-content\/uploads\/2023\/08\/ASEANNetwork-Skowrung.SB_.jpg\" alt=\"\" class=\"wp-image-15950\" style=\"object-fit:cover\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e17\u0e32\u0e07 AUN-CA \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Dialogues Research Forum \u0e41\u0e25\u0e30 Crosslight Learning Sessions &amp; Arts Festival \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07 \u0e14\u0e49\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e15\u0e48\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07 \u0e42\u0e04\u0e42\u0e23\u0e19\u0e32\u0e44\u0e27\u0e23\u0e31\u0e2a \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01 ASEAN University Network on Culture and the Arts \u0e0a\u0e48\u0e2d\u0e07\u0e22\u0e39\u0e17\u0e39\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07 ASEAN University Network<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1000\" height=\"533\" src=\"https:\/\/lc.mahidol.ac.th\/wp-content\/uploads\/2023\/08\/ASEANNetwork-Skowrung.SB-01.jpg\" alt=\"\" class=\"wp-image-15731\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e19\u0e31\u0e19\u0e18\u0e34\u0e14\u0e32 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e07\u0e28\u0e38 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e44\u0e14\u0e49\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 Moken Music and Revitalization: An Analysis from Participatory Action Research to Sustain Community\u2019s Cultural Heritage \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Dialogues Research Forum \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e47\u0e27 \u0e46 \u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e19\u0e35\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e14\u0e19\u0e15\u0e23\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e21\u0e2d\u0e41\u0e01\u0e19 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e19\u0e35\u0e49\u0e21\u0e35\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e0a\u0e38\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e14\u0e19\u0e15\u0e23\u0e35\u0e01\u0e25\u0e38\u0e48\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e21\u0e2d\u0e41\u0e01\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2b\u0e21\u0e39\u0e48\u0e40\u0e01\u0e32\u0e30 \u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1e\u0e31\u0e07\u0e07\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e21\u0e23\u0e14\u0e01\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e31\u0e1a\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e21\u0e2d\u0e41\u0e01\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e04\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e17\u0e38\u0e19\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e14\u0e19\u0e15\u0e23\u0e35\u0e21\u0e2d\u0e41\u0e01\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1000\" height=\"533\" src=\"https:\/\/lc.mahidol.ac.th\/wp-content\/uploads\/2023\/08\/ASEANNetwork-Skowrung.SB-04.jpg\" alt=\"\" class=\"wp-image-15733\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Crosslight Learning Sessions &amp; Arts Festival \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Arts Festival \u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 Design Art Exhibit (\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a) Film Festival (\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c) \u0e41\u0e25\u0e30 Performance Showcase (\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07) \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e42\u0e14\u0e22 \u0e14\u0e23.\u0e2a\u0e01\u0e32\u0e27\u0e23\u0e38\u0e49\u0e07 \u0e2a\u0e32\u0e22\u0e1a\u0e38\u0e0d\u0e21\u0e35 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e01\u0e49\u0e32\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e44\u0e14\u0e49\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e0a\u0e38\u0e14 Dvaravati Sri Suvarnabhumi (Pusa ASEAN: ASEAN Textile) \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 Performance Showcase \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e0a\u0e38\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e01\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e1c\u0e49\u0e32\u0e21\u0e31\u0e14\u0e2b\u0e21\u0e35\u0e48\u0e17\u0e35\u0e48 \u0e1e\u0e1a\u0e40\u0e2b\u0e47\u0e19\u0e17\u0e31\u0e48\u0e27\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e2d\u0e32\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e42\u0e14\u0e22\u0e19\u0e33\u0e1a\u0e17\u0e40\u0e1e\u0e25\u0e07\u0e41\u0e25\u0e30\u0e17\u0e48\u0e32\u0e23\u0e33\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e33\u0e17\u0e27\u0e32\u0e23\u0e27\u0e14\u0e35\u0e17\u0e35\u0e48 \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e28\u0e34\u0e25\u0e1b\u0e32\u0e01\u0e23\u0e41\u0e15\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e1b\u0e35 \u0e1e.\u0e28.2510 \u0e21\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2d\u0e32\u0e23\u0e22\u0e18\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e21-\u0e21\u0e2d\u0e0d\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e23\u0e22\u0e18\u0e23\u0e23\u0e21\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e1c\u0e49\u0e32\u0e21\u0e31\u0e14\u0e2b\u0e21\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48 \u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e42\u0e25\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e34\u0e14\u0e25\u0e41\u0e25\u0e30\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e17\u0e35\u0e48\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e04\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e2d\u0e32\u0e23\u0e22\u0e18\u0e23\u0e23\u0e21\u0e17\u0e27\u0e32\u0e23\u0e27\u0e14\u0e35\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e17\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22 \u0e46 \u0e04\u0e19\u0e04\u0e38\u0e49\u0e19\u0e0a\u0e34\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48 \u0e23\u0e30\u0e1a\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32\u0e44\u0e27\u0e23\u0e31\u0e2a \u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e08\u0e30\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e15\u0e23\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e22\u0e31\u0e07\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e15\u0e23\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e1a\u0e1b\u0e30\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"534\" src=\"https:\/\/lc.mahidol.ac.th\/wp-content\/uploads\/2023\/08\/ASEANNetwork-Skowrung.SB-03.jpg\" alt=\"\" class=\"wp-image-15735\"\/><\/figure>\n<\/div>","protected":false},"featured_media":15950,"template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"class_list":["post-15694","research-matter","type-research-matter","status-publish","has-post-thumbnail","hentry"],"taxonomy_info":[],"featured_image_src_large":["https:\/\/lc.mahidol.ac.th\/wp-content\/uploads\/2023\/08\/ASEANNetwork-Skowrung.SB_.jpg",1024,598,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/lc.mahidol.ac.th\/en\/wp-json\/wp\/v2\/research-matter\/15694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lc.mahidol.ac.th\/en\/wp-json\/wp\/v2\/research-matter"}],"about":[{"href":"https:\/\/lc.mahidol.ac.th\/en\/wp-json\/wp\/v2\/types\/research-matter"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lc.mahidol.ac.th\/en\/wp-json\/wp\/v2\/media\/15950"}],"wp:attachment":[{"href":"https:\/\/lc.mahidol.ac.th\/en\/wp-json\/wp\/v2\/media?parent=15694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}